{"id":92573,"date":"2024-06-21T23:25:41","date_gmt":"2024-06-21T21:25:41","guid":{"rendered":"https:\/\/mellos1986.com\/rimborso_reso\/"},"modified":"2024-07-09T18:35:15","modified_gmt":"2024-07-09T16:35:15","slug":"rimborso_reso","status":"publish","type":"page","link":"https:\/\/mellos1986.com\/de\/rimborso_reso\/","title":{"rendered":"R\u00fcckerstattung und R\u00fcckgaberecht"},"content":{"rendered":"&#13;\n<p class=\"wp-block-paragraph\"><b>Dies ist eine Beispielseite.<\/b><\/p>&#13;&#13;\n<h3>Overview<\/h3>&#13;&#13;\n<p class=\"wp-block-paragraph\">Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">To be eligible for a return, your item must be unused and in the same condition that you received it. Es muss au\u00dferdem in der Originalverpackung sein.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Einige Arten von Waren sind von der R\u00fcckgabe ausgenommen. Verderbliche Waren wie Lebensmittel, Blumen, Zeitungen oder Zeitschriften k\u00f6nnen nicht zur\u00fcckgegeben werden. Wir nehmen auch keine Produkte an, bei denen es sich um Intim- oder Hygieneartikel, gef\u00e4hrliche Materialien oder entflammbare Fl\u00fcssigkeiten oder Gase handelt.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Zus\u00e4tzliche Artikel, die nicht zur\u00fcckgegeben werden k\u00f6nnen:<\/p>&#13;&#13;\n<ul class=\"wp-block-list\">&#13;\n<li>Geschenkkarten<\/li>&#13;\n<li>Herunterladbare Software-Produkte<\/li>&#13;\n<li>Einige Artikel f\u00fcr Gesundheit und K\u00f6rperpflege<\/li>&#13;\n<\/ul>&#13;&#13;\n<p class=\"wp-block-paragraph\">Um Ihre R\u00fcckgabe abzuschlie\u00dfen, ben\u00f6tigen wir eine Quittung oder einen Kaufbeleg.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Bitte senden Sie Ihren Kauf nicht an den Hersteller zur\u00fcck.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Es gibt bestimmte Situationen, in denen nur Teilerstattungen gew\u00e4hrt werden:<\/p>&#13;&#13;\n<ul class=\"wp-block-list\">&#13;\n<li>Buch mit deutlichen Gebrauchsspuren<\/li>&#13;\n<li>CD, DVD, VHS-Kassette, Software, Videospiel, Kassette oder Schallplatte, die ge\u00f6ffnet wurde.<\/li>&#13;\n<li>Jeder Artikel, der sich nicht im Originalzustand befindet, besch\u00e4digt ist oder dem Teile fehlen, die nicht auf unseren Fehler zur\u00fcckzuf\u00fchren sind.<\/li>&#13;\n<li>Jeder Artikel, der mehr als 30 Tage nach der Lieferung zur\u00fcckgegeben wird<\/li>&#13;\n<\/ul>&#13;&#13;\n<h2>Refunds<\/h2>&#13;&#13;\n<p class=\"wp-block-paragraph\">Sobald wir Ihre R\u00fccksendung erhalten und gepr\u00fcft haben, senden wir Ihnen eine E-Mail, um Sie zu benachrichtigen, dass wir Ihren zur\u00fcckgesandten Artikel erhalten haben. Wir werden Sie auch \u00fcber die Genehmigung oder Ablehnung Ihrer Erstattung informieren.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie die Genehmigung erhalten, wird Ihre R\u00fcckerstattung bearbeitet und eine Gutschrift auf Ihre Kreditkarte oder Ihre urspr\u00fcngliche Zahlungsmethode wird automatisch innerhalb einer bestimmten Anzahl von Tagen vorgenommen.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\"><b>Versp\u00e4tete oder fehlende Erstattungen<\/b><\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie noch keine R\u00fcckerstattung erhalten haben, \u00fcberpr\u00fcfen Sie zun\u00e4chst noch einmal Ihr Bankkonto.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenden Sie sich dann an Ihr Kreditkartenunternehmen. Es kann einige Zeit dauern, bis Ihre Erstattung offiziell verbucht wird.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenden Sie sich dann an Ihre Bank. Bis eine Erstattung verbucht wird, vergeht oft eine gewisse Bearbeitungszeit.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie all dies getan haben und Ihre R\u00fcckerstattung immer noch nicht erhalten haben, kontaktieren Sie uns bitte unter {E-Mail-Adresse}.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\"><b>Verkaufsartikel<\/b><\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Nur Artikel zum regul\u00e4ren Preis k\u00f6nnen erstattet werden. Verkaufte Artikel k\u00f6nnen nicht zur\u00fcckerstattet werden.<\/p>&#13;&#13;\n<h2>Exchanges<\/h2>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wir ersetzen Artikel nur, wenn sie defekt oder besch\u00e4digt sind. Wenn Sie ihn gegen den gleichen Artikel umtauschen m\u00f6chten, senden Sie uns eine E-Mail an {E-Mail-Adresse} und schicken Sie Ihren Artikel an {Physikalische Adresse}: {Physikalische Adresse}.<\/p>&#13;&#13;\n<h2>Gifts<\/h2>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenn der Artikel beim Kauf als Geschenk gekennzeichnet war und direkt an Sie versandt wurde, erhalten Sie eine Geschenkgutschrift im Wert Ihrer R\u00fccksendung. Sobald der zur\u00fcckgegebene Artikel eingegangen ist, wird Ihnen ein Geschenkgutschein zugeschickt.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenn der Artikel beim Kauf nicht als Geschenk gekennzeichnet war oder der Schenkende die Bestellung an sich selbst geschickt hat, um sie Ihnen sp\u00e4ter zu schenken, senden wir eine R\u00fcckerstattung an den Schenkenden und er wird von Ihrer R\u00fcckgabe erfahren.<\/p>&#13;&#13;\n<h2>Shipping returns<\/h2>&#13;&#13;\n<p class=\"wp-block-paragraph\">Um Ihr Produkt zur\u00fcckzusenden, schicken Sie es bitte an: {Physikalische Adresse}.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Sie m\u00fcssen die Versandkosten f\u00fcr die R\u00fccksendung Ihres Artikels selbst tragen. Die Versandkosten sind nicht erstattungsf\u00e4hig. If you receive a refund, the cost of return shipping will be deducted from your refund.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Depending on where you live, the time it may take for your exchanged product to reach you may vary.<\/p>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenn Sie teurere Artikel zur\u00fcckschicken, sollten Sie einen verfolgbaren Versanddienst nutzen oder eine Versandversicherung abschlie\u00dfen. Wir garantieren nicht, dass wir Ihren zur\u00fcckgesandten Artikel erhalten.<\/p>&#13;&#13;\n<h2>Need help?<\/h2>&#13;&#13;\n<p class=\"wp-block-paragraph\">Wenden Sie sich bei Fragen zu Erstattungen und R\u00fcckgaben an {email}.<\/p>&#13;","protected":false},"excerpt":{"rendered":"<p>&#13; Dies ist eine Beispielseite. &#13;&#13; Overview &#13;&#13; Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. &#13;&#13; To be eligible for a return, your item must be unused and in the same condition that you received it. Es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-92573","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mellos1986.com\/de\/rimborso_reso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Outdoor technische Sportbekleidung | Mello&#039;s | Technische Sportbekleidung, aus Berg\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"R\u00fcckerstattung und R\u00fcckgaberecht | Outdoor technische Sportbekleidung | Mello&#039;s\" \/>\n\t\t<meta property=\"og:description\" content=\"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mellos1986.com\/de\/rimborso_reso\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"87\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-06-21T21:25:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-09T16:35:15+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mellosbutterfly\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@MELLOSBUTTERFLY\" \/>\n\t\t<meta name=\"twitter:title\" content=\"R\u00fcckerstattung und R\u00fcckgaberecht | Outdoor technische Sportbekleidung | Mello&#039;s\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@MELLOSBUTTERFLY\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/#listItem\",\"name\":\"R\\u00fcckerstattung und R\\u00fcckgaberecht\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/#listItem\",\"position\":2,\"name\":\"R\\u00fcckerstattung und R\\u00fcckgaberecht\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/#organization\",\"name\":\"Mello's\",\"description\":\"Abbigliamento tecnico sportivo da montagna Made in Italy dal 1986.\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/\",\"foundingDate\":\"1986-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":9},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-nero-mellos.png?wsr\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/#organizationLogo\",\"width\":300,\"height\":87,\"caption\":\"Logo Mello's\"},\"image\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mellosbutterfly\",\"https:\\\/\\\/x.com\\\/MELLOSBUTTERFLY\",\"https:\\\/\\\/www.instagram.com\\\/mellos_butterfly\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/#webpage\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/\",\"name\":\"R\\u00fcckerstattung und R\\u00fcckgaberecht | Outdoor technische Sportbekleidung | Mello's\",\"description\":\"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\\u00fcckgaberecht betr\\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\\u00f6nnen wir Ihnen keine volle R\\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/rimborso_reso\\\/#breadcrumblist\"},\"datePublished\":\"2024-06-21T23:25:41+02:00\",\"dateModified\":\"2024-07-09T18:35:15+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/\",\"name\":\"Outdoor technische Sportbekleidung | Mello's\",\"description\":\"Technische Sportbekleidung, aus Berg\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"R\u00fcckerstattung und R\u00fcckgaberecht | Outdoor technische Sportbekleidung | Mello's","description":"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es","canonical_url":"https:\/\/mellos1986.com\/de\/rimborso_reso\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mellos1986.com\/de\/rimborso_reso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/mellos1986.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/de\/rimborso_reso\/#listItem","name":"R\u00fcckerstattung und R\u00fcckgaberecht"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/de\/rimborso_reso\/#listItem","position":2,"name":"R\u00fcckerstattung und R\u00fcckgaberecht","previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/de\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/mellos1986.com\/de\/#organization","name":"Mello's","description":"Abbigliamento tecnico sportivo da montagna Made in Italy dal 1986.","url":"https:\/\/mellos1986.com\/de\/","foundingDate":"1986-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":9},"logo":{"@type":"ImageObject","url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","@id":"https:\/\/mellos1986.com\/de\/rimborso_reso\/#organizationLogo","width":300,"height":87,"caption":"Logo Mello's"},"image":{"@id":"https:\/\/mellos1986.com\/de\/rimborso_reso\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/mellosbutterfly","https:\/\/x.com\/MELLOSBUTTERFLY","https:\/\/www.instagram.com\/mellos_butterfly\/"]},{"@type":"WebPage","@id":"https:\/\/mellos1986.com\/de\/rimborso_reso\/#webpage","url":"https:\/\/mellos1986.com\/de\/rimborso_reso\/","name":"R\u00fcckerstattung und R\u00fcckgaberecht | Outdoor technische Sportbekleidung | Mello's","description":"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/mellos1986.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/mellos1986.com\/de\/rimborso_reso\/#breadcrumblist"},"datePublished":"2024-06-21T23:25:41+02:00","dateModified":"2024-07-09T18:35:15+02:00"},{"@type":"WebSite","@id":"https:\/\/mellos1986.com\/de\/#website","url":"https:\/\/mellos1986.com\/de\/","name":"Outdoor technische Sportbekleidung | Mello's","description":"Technische Sportbekleidung, aus Berg","inLanguage":"de-DE","publisher":{"@id":"https:\/\/mellos1986.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Outdoor technische Sportbekleidung | Mello's | Technische Sportbekleidung, aus Berg","og:type":"article","og:title":"R\u00fcckerstattung und R\u00fcckgaberecht | Outdoor technische Sportbekleidung | Mello's","og:description":"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es","og:url":"https:\/\/mellos1986.com\/de\/rimborso_reso\/","og:image":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","og:image:secure_url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","og:image:width":300,"og:image:height":87,"article:published_time":"2024-06-21T21:25:41+00:00","article:modified_time":"2024-07-09T16:35:15+00:00","article:publisher":"https:\/\/www.facebook.com\/mellosbutterfly","twitter:card":"summary_large_image","twitter:site":"@MELLOSBUTTERFLY","twitter:title":"R\u00fcckerstattung und R\u00fcckgaberecht | Outdoor technische Sportbekleidung | Mello's","twitter:description":"Dies ist eine Beispielseite. Overview Unser Erstattungs- und R\u00fcckgaberecht betr\u00e4gt 30 Tage. Wenn seit Ihrem Kauf 30 Tage vergangen sind, k\u00f6nnen wir Ihnen keine volle R\u00fcckerstattung oder einen Umtausch anbieten. To be eligible for a return, your item must be unused and in the same condition that you received it. Es","twitter:creator":"@MELLOSBUTTERFLY","twitter:image":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr"},"aioseo_meta_data":{"post_id":"92573","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2024-08-11 16:35:30","updated":"2026-08-09 14:53:31","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tR\u00fcckerstattung und R\u00fcckgaberecht\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mellos1986.com\/de\/"},{"label":"R\u00fcckerstattung und R\u00fcckgaberecht","link":"https:\/\/mellos1986.com\/de\/rimborso_reso\/"}],"_links":{"self":[{"href":"https:\/\/mellos1986.com\/de\/wp-json\/wp\/v2\/pages\/92573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mellos1986.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mellos1986.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mellos1986.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mellos1986.com\/de\/wp-json\/wp\/v2\/comments?post=92573"}],"version-history":[{"count":0,"href":"https:\/\/mellos1986.com\/de\/wp-json\/wp\/v2\/pages\/92573\/revisions"}],"wp:attachment":[{"href":"https:\/\/mellos1986.com\/de\/wp-json\/wp\/v2\/media?parent=92573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}