{"id":82210,"date":"2020-07-31T12:22:05","date_gmt":"2020-07-31T10:22:14","guid":{"rendered":"https:\/\/mellos1986.com\/?post_type=product&#038;p=82210"},"modified":"2020-10-03T19:26:27","modified_gmt":"2020-10-03T17:26:27","slug":"chaussures-de-randonnee-easy","status":"publish","type":"product","link":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/","title":{"rendered":"CHAUSSURES DE RANDONNEE EASY"},"content":{"rendered":"<h2><span style=\"color: #ff0000;\"> Chaussures de randonn\u00e9e Easy. unisexe | Mello&rsquo;s<\/span><\/h2>\n<p><strong>Chaussures de randonn\u00e9e<\/strong><\/p>\n<ul>\n<li>Id\u00e9al pour des excursions tranquilles.<\/li>\n<li>Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr.<\/li>\n<li>La chaussure garantit une r\u00e9ponse s\u00fbre et garantit un maintien s\u00fbr et confortable et une r\u00e9sistance maximale.<\/li>\n<li>Confortable, ergonomique et avec languette rembourr\u00e9e, qui offre un soutien au pied dans chaque phase de mouvement.<\/li>\n<li>Enti\u00e8rement doubl\u00e9 en Nubuck, il prot\u00e8ge le pied du vent et de l&rsquo;humidit\u00e9, r\u00e9gule la transpiration et le rend adapt\u00e9 pour les saisons d&rsquo;\u00e9t\u00e9 et d&rsquo;hiver avec des chaussettes plus lourdes.<\/li>\n<li>Fabriqu\u00e9 en Italie.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Chaussures de randonn\u00e9e. <\/strong>Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr.<\/p>\n<p>Activit\u00e9s:<\/p>\n<p><a href=\"https:\/\/mellos1986.com\/fr\/tag-prodotto\/trekking-fr\/\"><img decoding=\"async\" class=\"alignnone wp-image-66181 size-full\" src=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2019\/09\/icona-trekking_1.png\" alt=\"\" width=\"50\" height=\"50\" align=\"middle\" \/><\/a> Trekking<\/p>\n<p>Caract\u00e9ristiques:<\/p>\n<p><a href=\"https:\/\/mellos1986.com\/fr\/tag-prodotto\/confortable\/\"><img decoding=\"async\" class=\"alignnone wp-image-15882 size-full\" src=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2016\/08\/performance_confortevole-e1567977047268.png\" alt=\"Confortevole | Performance | Mello's\" width=\"50\" height=\"50\" align=\"middle\" \/><\/a> Confortable\u00a0 <a href=\"https:\/\/mellos1986.com\/fr\/tag-prodotto\/leger\/\"><img decoding=\"async\" class=\"alignnone wp-image-15892 size-full\" src=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2016\/08\/performance_leggero-e1567977032100.png\" alt=\"Leggero | Performance | Mello's\" width=\"50\" height=\"50\" align=\"middle\" \/><\/a> L\u00e9ger\u00a0 <a href=\"https:\/\/mellos1986.com\/fr\/tag-prodotto\/made-in-italy-fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15912 size-full\" src=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2016\/08\/performance_made_in_italy-e1567977003613.png\" alt=\"Made in Italy | Performance | Mello's\" width=\"50\" height=\"50\" align=\"middle\" \/><\/a> Made in Italy<\/p>\n","protected":false},"featured_media":84412,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[1932,1843],"product_tag":[684,692,1722],"class_list":["post-82210","product","type-product","status-publish","has-post-thumbnail","product_cat-chaussures-sacs-a-dos-et-equipement","product_cat-nouveautes","product_tag-confortable","product_tag-leger","product_tag-trekking-fr","first","outofstock","shipping-taxable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Chaussures de randonn\u00e9e. Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr. Activit\u00e9s: Trekking Caract\u00e9ristiques: Confortable L\u00e9ger Made in Italy\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"V\u00eatements de sport Outdoor | Mello&#039;s | V\u00eatements techniques de sports de montagne\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CHAUSSURES DE RANDONNEE EASY | V\u00eatements de sport Outdoor | Mello&#039;s\" \/>\n\t\t<meta property=\"og:description\" content=\"Chaussures de randonn\u00e9e. Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr. Activit\u00e9s: Trekking Caract\u00e9ristiques: Confortable L\u00e9ger Made in Italy\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"87\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-07-31T10:22:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-10-03T17:26:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mellosbutterfly\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@MELLOSBUTTERFLY\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CHAUSSURES DE RANDONNEE EASY | V\u00eatements de sport Outdoor | Mello&#039;s\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Chaussures de randonn\u00e9e. Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr. Activit\u00e9s: Trekking Caract\u00e9ristiques: Confortable L\u00e9ger Made in Italy\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/#listItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/nouveautes\\\/#listItem\",\"name\":\"Nouveaut\\u00e9s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/nouveautes\\\/#listItem\",\"position\":3,\"name\":\"Nouveaut\\u00e9s\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/nouveautes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#listItem\",\"name\":\"CHAUSSURES DE RANDONNEE EASY\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#listItem\",\"position\":4,\"name\":\"CHAUSSURES DE RANDONNEE EASY\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/nouveautes\\\/#listItem\",\"name\":\"Nouveaut\\u00e9s\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#itempage\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/\",\"name\":\"CHAUSSURES DE RANDONNEE EASY | V\\u00eatements de sport Outdoor | Mello's\",\"description\":\"Chaussures de randonn\\u00e9e. Id\\u00e9al pour des excursions tranquilles. Un profil antid\\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\\u00fbr. Activit\\u00e9s: Trekking Caract\\u00e9ristiques: Confortable L\\u00e9ger Made in Italy\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/GMX216TC999-004-F-1.jpg?wsr\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#mainImage\",\"width\":500,\"height\":750,\"caption\":\"Chaussures de randonnee easy\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#mainImage\"},\"datePublished\":\"2020-07-31T12:22:05+02:00\",\"dateModified\":\"2020-10-03T19:26:27+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#organization\",\"name\":\"Mello's\",\"description\":\"Abbigliamento tecnico sportivo da montagna Made in Italy dal 1986.\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/\",\"foundingDate\":\"1986-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":9},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-nero-mellos.png?wsr\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#organizationLogo\",\"width\":300,\"height\":87,\"caption\":\"Logo Mello's\"},\"image\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/chaussures-de-randonnee-easy\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mellosbutterfly\",\"https:\\\/\\\/x.com\\\/MELLOSBUTTERFLY\",\"https:\\\/\\\/www.instagram.com\\\/mellos_butterfly\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/\",\"name\":\"V\\u00eatements de sport Outdoor | Mello's\",\"description\":\"V\\u00eatements techniques de sports de montagne\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CHAUSSURES DE RANDONNEE EASY | V\u00eatements de sport Outdoor | Mello's","description":"Chaussures de randonn\u00e9e. Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr. Activit\u00e9s: Trekking Caract\u00e9ristiques: Confortable L\u00e9ger Made in Italy","canonical_url":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/mellos1986.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/#listItem","position":2,"name":"Boutique","item":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/nouveautes\/#listItem","name":"Nouveaut\u00e9s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/nouveautes\/#listItem","position":3,"name":"Nouveaut\u00e9s","item":"https:\/\/mellos1986.com\/fr\/nouveautes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#listItem","name":"CHAUSSURES DE RANDONNEE EASY"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#listItem","position":4,"name":"CHAUSSURES DE RANDONNEE EASY","previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/nouveautes\/#listItem","name":"Nouveaut\u00e9s"}}]},{"@type":"ItemPage","@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#itempage","url":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/","name":"CHAUSSURES DE RANDONNEE EASY | V\u00eatements de sport Outdoor | Mello's","description":"Chaussures de randonn\u00e9e. Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr. Activit\u00e9s: Trekking Caract\u00e9ristiques: Confortable L\u00e9ger Made in Italy","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/mellos1986.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2020\/10\/GMX216TC999-004-F-1.jpg?wsr","@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#mainImage","width":500,"height":750,"caption":"Chaussures de randonnee easy"},"primaryImageOfPage":{"@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#mainImage"},"datePublished":"2020-07-31T12:22:05+02:00","dateModified":"2020-10-03T19:26:27+02:00"},{"@type":"Organization","@id":"https:\/\/mellos1986.com\/fr\/#organization","name":"Mello's","description":"Abbigliamento tecnico sportivo da montagna Made in Italy dal 1986.","url":"https:\/\/mellos1986.com\/fr\/","foundingDate":"1986-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":9},"logo":{"@type":"ImageObject","url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#organizationLogo","width":300,"height":87,"caption":"Logo Mello's"},"image":{"@id":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/mellosbutterfly","https:\/\/x.com\/MELLOSBUTTERFLY","https:\/\/www.instagram.com\/mellos_butterfly\/"]},{"@type":"WebSite","@id":"https:\/\/mellos1986.com\/fr\/#website","url":"https:\/\/mellos1986.com\/fr\/","name":"V\u00eatements de sport Outdoor | Mello's","description":"V\u00eatements techniques de sports de montagne","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/mellos1986.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"V\u00eatements de sport Outdoor | Mello's | V\u00eatements techniques de sports de montagne","og:type":"article","og:title":"CHAUSSURES DE RANDONNEE EASY | V\u00eatements de sport Outdoor | Mello's","og:description":"Chaussures de randonn\u00e9e. Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr. Activit\u00e9s: Trekking Caract\u00e9ristiques: Confortable L\u00e9ger Made in Italy","og:url":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/","og:image":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","og:image:secure_url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","og:image:width":300,"og:image:height":87,"article:published_time":"2020-07-31T10:22:14+00:00","article:modified_time":"2020-10-03T17:26:27+00:00","article:publisher":"https:\/\/www.facebook.com\/mellosbutterfly","twitter:card":"summary_large_image","twitter:site":"@MELLOSBUTTERFLY","twitter:title":"CHAUSSURES DE RANDONNEE EASY | V\u00eatements de sport Outdoor | Mello's","twitter:description":"Chaussures de randonn\u00e9e. Id\u00e9al pour des excursions tranquilles. Un profil antid\u00e9rapant et une semelle Vibram avec une technologie de pointe et durable de la semelle permettent un ajustement confortable et s\u00fbr. Activit\u00e9s: Trekking Caract\u00e9ristiques: Confortable L\u00e9ger Made in Italy","twitter:image":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr"},"aioseo_meta_data":{"post_id":"82210","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2024-08-11 17:23:50","updated":"2026-08-09 16:45:31","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/\" title=\"Boutique\">Boutique<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/fr\/nouveautes\/\" title=\"Nouveaut\u00e9s\">Nouveaut\u00e9s<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCHAUSSURES DE RANDONNEE EASY\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mellos1986.com\/fr\/"},{"label":"Boutique","link":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/"},{"label":"Nouveaut\u00e9s","link":"https:\/\/mellos1986.com\/fr\/nouveautes\/"},{"label":"CHAUSSURES DE RANDONNEE EASY","link":"https:\/\/mellos1986.com\/fr\/produit\/chaussures-de-randonnee-easy\/"}],"_links":{"self":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product\/82210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/comments?post=82210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/media\/84412"}],"wp:attachment":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/media?parent=82210"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product_brand?post=82210"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product_cat?post=82210"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product_tag?post=82210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}