{"id":97668,"date":"2026-09-01T05:56:05","date_gmt":"2026-09-01T03:56:05","guid":{"rendered":"https:\/\/mellos1986.com\/artic-lady-veste-en-ecoplumes-sorona-sustans\/"},"modified":"2026-09-01T05:56:05","modified_gmt":"2026-09-01T03:56:05","slug":"artic-lady-veste-en-ecoplumes-sorona-sustans","status":"publish","type":"product","link":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/","title":{"rendered":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS"},"content":{"rendered":"<p>Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l&rsquo;usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l&rsquo;eau (colonne d&rsquo;eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l&rsquo;usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l&rsquo;eau (colonne d&rsquo;eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.<\/p>\n","protected":false},"featured_media":75600,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[627,1840,236],"product_tag":[],"class_list":["post-97668","product","type-product","status-publish","has-post-thumbnail","product_cat-chaquetas-deportivas-para-mujeres","product_cat-recien-llegados","product_cat-ropa-deportiva-tecnica-para-mujeres","first","instock","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l&#039;usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l&#039;eau (colonne d&#039;eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"V\u00eatements de sport Outdoor | Mello&#039;s | V\u00eatements techniques de sports de montagne\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Artic Lady veste en \u00e9coplumes SORONA SUSTANS | V\u00eatements de sport Outdoor | Mello&#039;s\" \/>\n\t\t<meta property=\"og:description\" content=\"Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l&#039;usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l&#039;eau (colonne d&#039;eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"87\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-09-01T03:56:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-09-01T03:56:05+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mellosbutterfly\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@MELLOSBUTTERFLY\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Artic Lady veste en \u00e9coplumes SORONA SUSTANS | V\u00eatements de sport Outdoor | Mello&#039;s\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l&#039;usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l&#039;eau (colonne d&#039;eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/#listItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/#listItem\",\"name\":\"Ropa deportiva t\\u00e9cnica para mujeres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/#listItem\",\"position\":3,\"name\":\"Ropa deportiva t\\u00e9cnica para mujeres\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/chaquetas-deportivas-para-mujeres\\\/#listItem\",\"name\":\"Chaquetas deportivas para mujeres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/vetements-techniques-de-sports-outdoor\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/chaquetas-deportivas-para-mujeres\\\/#listItem\",\"position\":4,\"name\":\"Chaquetas deportivas para mujeres\",\"item\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/chaquetas-deportivas-para-mujeres\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#listItem\",\"name\":\"Artic Lady veste en \\u00e9coplumes SORONA SUSTANS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/#listItem\",\"name\":\"Ropa deportiva t\\u00e9cnica para mujeres\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#listItem\",\"position\":5,\"name\":\"Artic Lady veste en \\u00e9coplumes SORONA SUSTANS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/es\\\/ropa-deportiva-tecnica-para-mujeres\\\/chaquetas-deportivas-para-mujeres\\\/#listItem\",\"name\":\"Chaquetas deportivas para mujeres\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#itempage\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/\",\"name\":\"Artic Lady veste en \\u00e9coplumes SORONA SUSTANS | V\\u00eatements de sport Outdoor | Mello's\",\"description\":\"Veste en \\u00e9coplumes SORONA SUSTANS en tissu nylon r\\u00e9sistant \\u00e0 l'usure, l\\u00e9ger et r\\u00e9sistant, trait\\u00e9 avec un rev\\u00eatement microporeux \\u00e9tanche \\u00e0 l'eau (colonne d'eau 600 mm) et respirant (5 000 g\\\/m\\u00b2\\\/24h). Activit\\u00e9 : Ski, Ski de randonn\\u00e9e, Alpinisme, Raquettes \\u00e0 neige. Caract\\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/GMD202TC402-916_F-1.jpg?wsr\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#mainImage\",\"width\":500,\"height\":750,\"caption\":\"Chaqueta ecodown artic lady\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#mainImage\"},\"datePublished\":\"2026-09-01T05:56:05+02:00\",\"dateModified\":\"2026-09-01T05:56:05+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#organization\",\"name\":\"Mello's\",\"description\":\"Abbigliamento tecnico sportivo da montagna Made in Italy dal 1986.\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/\",\"foundingDate\":\"1986-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":9},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo-nero-mellos.png?wsr\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#organizationLogo\",\"width\":300,\"height\":87,\"caption\":\"Logo Mello's\"},\"image\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/produit\\\/artic-lady-veste-en-ecoplumes-sorona-sustans\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mellosbutterfly\",\"https:\\\/\\\/x.com\\\/MELLOSBUTTERFLY\",\"https:\\\/\\\/www.instagram.com\\\/mellos_butterfly\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/\",\"name\":\"V\\u00eatements de sport Outdoor | Mello's\",\"description\":\"V\\u00eatements techniques de sports de montagne\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/mellos1986.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS | V\u00eatements de sport Outdoor | Mello's","description":"Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l'usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l'eau (colonne d'eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.","canonical_url":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/mellos1986.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/#listItem","position":2,"name":"Boutique","item":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/#listItem","name":"Ropa deportiva t\u00e9cnica para mujeres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/#listItem","position":3,"name":"Ropa deportiva t\u00e9cnica para mujeres","item":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/chaquetas-deportivas-para-mujeres\/#listItem","name":"Chaquetas deportivas para mujeres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/chaquetas-deportivas-para-mujeres\/#listItem","position":4,"name":"Chaquetas deportivas para mujeres","item":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/chaquetas-deportivas-para-mujeres\/","nextItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#listItem","name":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/#listItem","name":"Ropa deportiva t\u00e9cnica para mujeres"}},{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#listItem","position":5,"name":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS","previousItem":{"@type":"ListItem","@id":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/chaquetas-deportivas-para-mujeres\/#listItem","name":"Chaquetas deportivas para mujeres"}}]},{"@type":"ItemPage","@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#itempage","url":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/","name":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS | V\u00eatements de sport Outdoor | Mello's","description":"Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l'usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l'eau (colonne d'eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/mellos1986.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2020\/02\/GMD202TC402-916_F-1.jpg?wsr","@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#mainImage","width":500,"height":750,"caption":"Chaqueta ecodown artic lady"},"primaryImageOfPage":{"@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#mainImage"},"datePublished":"2026-09-01T05:56:05+02:00","dateModified":"2026-09-01T05:56:05+02:00"},{"@type":"Organization","@id":"https:\/\/mellos1986.com\/fr\/#organization","name":"Mello's","description":"Abbigliamento tecnico sportivo da montagna Made in Italy dal 1986.","url":"https:\/\/mellos1986.com\/fr\/","foundingDate":"1986-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":9},"logo":{"@type":"ImageObject","url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#organizationLogo","width":300,"height":87,"caption":"Logo Mello's"},"image":{"@id":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/mellosbutterfly","https:\/\/x.com\/MELLOSBUTTERFLY","https:\/\/www.instagram.com\/mellos_butterfly\/"]},{"@type":"WebSite","@id":"https:\/\/mellos1986.com\/fr\/#website","url":"https:\/\/mellos1986.com\/fr\/","name":"V\u00eatements de sport Outdoor | Mello's","description":"V\u00eatements techniques de sports de montagne","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/mellos1986.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"V\u00eatements de sport Outdoor | Mello's | V\u00eatements techniques de sports de montagne","og:type":"article","og:title":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS | V\u00eatements de sport Outdoor | Mello's","og:description":"Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l'usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l'eau (colonne d'eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.","og:url":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/","og:image":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","og:image:secure_url":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr","og:image:width":300,"og:image:height":87,"article:published_time":"2026-09-01T03:56:05+00:00","article:modified_time":"2026-09-01T03:56:05+00:00","article:publisher":"https:\/\/www.facebook.com\/mellosbutterfly","twitter:card":"summary_large_image","twitter:site":"@MELLOSBUTTERFLY","twitter:title":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS | V\u00eatements de sport Outdoor | Mello's","twitter:description":"Veste en \u00e9coplumes SORONA SUSTANS en tissu nylon r\u00e9sistant \u00e0 l'usure, l\u00e9ger et r\u00e9sistant, trait\u00e9 avec un rev\u00eatement microporeux \u00e9tanche \u00e0 l'eau (colonne d'eau 600 mm) et respirant (5 000 g\/m\u00b2\/24h). Activit\u00e9 : Ski, Ski de randonn\u00e9e, Alpinisme, Raquettes \u00e0 neige. Caract\u00e9ristiques : Coupe-vent, Hydrofuge, Thermique.","twitter:image":"https:\/\/mellos1986.com\/wp-content\/uploads\/2023\/06\/logo-nero-mellos.png?wsr"},"aioseo_meta_data":{"post_id":"97668","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2026-09-01 03:58:11","updated":"2026-09-01 04:19:33","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/\" title=\"Boutique\">Boutique<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/\" title=\"Ropa deportiva t\u00e9cnica para mujeres\">Ropa deportiva t\u00e9cnica para mujeres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/chaquetas-deportivas-para-mujeres\/\" title=\"Chaquetas deportivas para mujeres\">Chaquetas deportivas para mujeres<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArtic Lady veste en \u00e9coplumes SORONA SUSTANS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/mellos1986.com\/fr\/"},{"label":"Boutique","link":"https:\/\/mellos1986.com\/fr\/vetements-techniques-de-sports-outdoor\/"},{"label":"Ropa deportiva t\u00e9cnica para mujeres","link":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/"},{"label":"Chaquetas deportivas para mujeres","link":"https:\/\/mellos1986.com\/es\/ropa-deportiva-tecnica-para-mujeres\/chaquetas-deportivas-para-mujeres\/"},{"label":"Artic Lady veste en \u00e9coplumes SORONA SUSTANS","link":"https:\/\/mellos1986.com\/fr\/produit\/artic-lady-veste-en-ecoplumes-sorona-sustans\/"}],"_links":{"self":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product\/97668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/comments?post=97668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/media\/75600"}],"wp:attachment":[{"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/media?parent=97668"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product_brand?post=97668"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product_cat?post=97668"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mellos1986.com\/fr\/wp-json\/wp\/v2\/product_tag?post=97668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}